{"id":11111,"date":"2023-05-15T10:50:06","date_gmt":"2023-05-15T09:50:06","guid":{"rendered":"https:\/\/www.lonesomepine.de\/?post_type=product&#038;p=11111"},"modified":"2025-12-30T18:35:27","modified_gmt":"2025-12-30T17:35:27","slug":"t-shirt-cow-girl","status":"publish","type":"product","link":"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl","title":{"rendered":"T-Shirt Cow Girl"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>T-Shirt mit Strass Applikationen<\/p>\n<p>&#8211; sch\u00f6ner halb V-Ausschnitt<br \/>\n&#8211; Pflegeleicht<\/p>","protected":false},"featured_media":11966,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[15,86],"product_tag":[],"class_list":["post-11111","product","type-product","status-publish","has-post-thumbnail","product_cat-damen","product_cat-tshirts","product_shipping_class-standard-versand","pa_farbe-schwarz","pa_groesse_franzoesisch-t2","pa_groesse_franzoesisch-t3","pa_groesse_franzoesisch-t4","pa_groesse_franzoesisch-t5","pa_groesse_franzoesisch-t1","pa_hersteller-graphi_tee","pa_material-100_baumwolle","pa_pflege-30-grad-feinwaesche-auf-links-kein-trockner","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"T-Shirt mit Strass Applikationen - sch\u00f6ner halb V-Ausschnitt - Pflegeleicht\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Lonesome Pine Westernshop -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"T-Shirt Cow Girl - Lonesome Pine Westernshop\" \/>\n\t\t<meta property=\"og:description\" content=\"T-Shirt mit Strass Applikationen - sch\u00f6ner halb V-Ausschnitt - Pflegeleicht\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2020\/04\/logo.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2020\/04\/logo.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-05-15T09:50:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-12-30T17:35:27+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"T-Shirt Cow Girl - Lonesome Pine Westernshop\" \/>\n\t\t<meta name=\"twitter:description\" content=\"T-Shirt mit Strass Applikationen - sch\u00f6ner halb V-Ausschnitt - Pflegeleicht\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2020\/04\/logo.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/t-shirt-cow-girl#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/shop-2#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/shop-2#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/shop-2\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/damen#listItem\",\"name\":\"DAMEN\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/damen#listItem\",\"position\":3,\"name\":\"DAMEN\",\"item\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/damen\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/damen\\\/tshirts#listItem\",\"name\":\"T-Shirts\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/shop-2#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/damen\\\/tshirts#listItem\",\"position\":4,\"name\":\"T-Shirts\",\"item\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/damen\\\/tshirts\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/t-shirt-cow-girl#listItem\",\"name\":\"T-Shirt Cow Girl\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/damen#listItem\",\"name\":\"DAMEN\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/t-shirt-cow-girl#listItem\",\"position\":5,\"name\":\"T-Shirt Cow Girl\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/damen\\\/tshirts#listItem\",\"name\":\"T-Shirts\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/t-shirt-cow-girl#itempage\",\"url\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/t-shirt-cow-girl\",\"name\":\"T-Shirt Cow Girl - Lonesome Pine Westernshop\",\"description\":\"T-Shirt mit Strass Applikationen - sch\\u00f6ner halb V-Ausschnitt - Pflegeleicht\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/t-shirt-cow-girl#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.lonesomepine.de\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/femme-au-chapeau-t-shirt-femme-col-v.jpg\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/t-shirt-cow-girl\\\/#mainImage\",\"width\":771,\"height\":1000,\"caption\":\"Shirt Cowgirl red Hat\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/t-shirt-cow-girl#mainImage\"},\"datePublished\":\"2023-05-15T10:50:06+01:00\",\"dateModified\":\"2025-12-30T18:35:27+01:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/#organization\",\"name\":\"Lonesome Pine Westernshop\",\"url\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.lonesomepine.de\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo.jpg\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/t-shirt-cow-girl\\\/#organizationLogo\",\"width\":612,\"height\":411,\"caption\":\"logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/t-shirt-cow-girl\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/\",\"name\":\"Lonesome Pine Westernshop\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"T-Shirt Cow Girl - Lonesome Pine Westernshop","description":"T-Shirt mit Strass Applikationen - sch\u00f6ner halb V-Ausschnitt - Pflegeleicht","canonical_url":"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/www.lonesomepine.de\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/shop-2#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/shop-2#listItem","position":2,"name":"Shop","item":"https:\/\/www.lonesomepine.de\/en\/shop-2","nextItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product-category\/damen#listItem","name":"DAMEN"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product-category\/damen#listItem","position":3,"name":"DAMEN","item":"https:\/\/www.lonesomepine.de\/en\/product-category\/damen","nextItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product-category\/damen\/tshirts#listItem","name":"T-Shirts"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/shop-2#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product-category\/damen\/tshirts#listItem","position":4,"name":"T-Shirts","item":"https:\/\/www.lonesomepine.de\/en\/product-category\/damen\/tshirts","nextItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl#listItem","name":"T-Shirt Cow Girl"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product-category\/damen#listItem","name":"DAMEN"}},{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl#listItem","position":5,"name":"T-Shirt Cow Girl","previousItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product-category\/damen\/tshirts#listItem","name":"T-Shirts"}}]},{"@type":"ItemPage","@id":"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl#itempage","url":"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl","name":"T-Shirt Cow Girl - Lonesome Pine Westernshop","description":"T-Shirt mit Strass Applikationen - sch\u00f6ner halb V-Ausschnitt - Pflegeleicht","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/www.lonesomepine.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2023\/05\/femme-au-chapeau-t-shirt-femme-col-v.jpg","@id":"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl\/#mainImage","width":771,"height":1000,"caption":"Shirt Cowgirl red Hat"},"primaryImageOfPage":{"@id":"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl#mainImage"},"datePublished":"2023-05-15T10:50:06+01:00","dateModified":"2025-12-30T18:35:27+01:00"},{"@type":"Organization","@id":"https:\/\/www.lonesomepine.de\/en\/#organization","name":"Lonesome Pine Westernshop","url":"https:\/\/www.lonesomepine.de\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2020\/04\/logo.jpg","@id":"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl\/#organizationLogo","width":612,"height":411,"caption":"logo"},"image":{"@id":"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/www.lonesomepine.de\/en\/#website","url":"https:\/\/www.lonesomepine.de\/en\/","name":"Lonesome Pine Westernshop","inLanguage":"en-GB","publisher":{"@id":"https:\/\/www.lonesomepine.de\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Lonesome Pine Westernshop -","og:type":"article","og:title":"T-Shirt Cow Girl - Lonesome Pine Westernshop","og:description":"T-Shirt mit Strass Applikationen - sch\u00f6ner halb V-Ausschnitt - Pflegeleicht","og:url":"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl","og:image":"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2020\/04\/logo.jpg","og:image:secure_url":"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2020\/04\/logo.jpg","article:published_time":"2023-05-15T09:50:06+00:00","article:modified_time":"2025-12-30T17:35:27+00:00","twitter:card":"summary","twitter:title":"T-Shirt Cow Girl - Lonesome Pine Westernshop","twitter:description":"T-Shirt mit Strass Applikationen - sch\u00f6ner halb V-Ausschnitt - Pflegeleicht","twitter:image":"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2020\/04\/logo.jpg"},"aioseo_meta_data":{"post_id":"11111","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"created":"2023-05-15 09:50:06","updated":"2026-06-21 17:49:22","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.lonesomepine.de\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.lonesomepine.de\/en\/shop-2\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.lonesomepine.de\/en\/product-category\/damen\" title=\"DAMEN\">DAMEN<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.lonesomepine.de\/en\/product-category\/damen\/tshirts\" title=\"T-Shirts\">T-Shirts<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tT-Shirt Cow Girl\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.lonesomepine.de\/en\/"},{"label":"Shop","link":"https:\/\/www.lonesomepine.de\/en\/shop-2"},{"label":"DAMEN","link":"https:\/\/www.lonesomepine.de\/en\/product-category\/damen"},{"label":"T-Shirts","link":"https:\/\/www.lonesomepine.de\/en\/product-category\/damen\/tshirts"},{"label":"T-Shirt Cow Girl","link":"https:\/\/www.lonesomepine.de\/en\/product\/t-shirt-cow-girl"}],"_links":{"self":[{"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/product\/11111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/comments?post=11111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/media\/11966"}],"wp:attachment":[{"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/media?parent=11111"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/product_brand?post=11111"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/product_cat?post=11111"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/product_tag?post=11111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}