{"id":4279,"date":"2020-02-13T08:39:02","date_gmt":"2020-02-13T07:39:02","guid":{"rendered":"https:\/\/lonesomepinewesternshop.apps-1and1.net\/?post_type=product&#038;p=4279"},"modified":"2026-05-08T16:51:04","modified_gmt":"2026-05-08T15:51:04","slug":"crossbody-tasche-l-117-black","status":"publish","type":"product","link":"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black","title":{"rendered":"Crossbody Tasche L-162 BK"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Crossbody Tasche mit Fransen<\/p>\n<p>&#8211; Handgearbeitete Ledertasche zum Aufh\u00e4ngen an den Hosenschlaufen<br \/>\n&#8211; R\u00fcckseite ein Fach mit Reissverschlu\u00df f\u00fcr Wichtige Dinge EC Karte und Geld<br \/>\n&#8211; Prima beim Tanzen oder zum Reiten da hat man alles wichtige dabei und die H\u00e4nde frei<br \/>\n&#8211; Schulterriemen vorhanden<br \/>\n&#8211; So das man sie auch zu einer Bodycrosstasche umfunktionieren kann<br \/>\n&#8211; Gr\u00f6\u00dfe: 17x20cm<\/p>","protected":false},"featured_media":11431,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[178],"product_tag":[478,486],"class_list":["post-4279","product","type-product","status-publish","has-post-thumbnail","product_cat-handtaschen-accessoires","product_tag-cowgirl-tasche","product_tag-bodycrosstasche","pa_farbe-schwarz","pa_hersteller-montana_west","pa_material-rindsleder","pa_pflege-keine_angabe","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Crossbody Tasche mit Fransen - Handgearbeitete Ledertasche zum Aufh\u00e4ngen an den Hosenschlaufen - R\u00fcckseite ein Fach mit Reissverschlu\u00df f\u00fcr Wichtige Dinge EC Karte und Geld - Prima beim Tanzen oder zum Reiten da hat man alles wichtige dabei und die H\u00e4nde frei - Schulterriemen vorhanden - So das man sie auch zu einer Bodycrosstasche umfunktionieren kann - Gr\u00f6\u00dfe: 17x20cm\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Lonesome Pine Westernshop -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Crossbody Tasche L-162 BK - Lonesome Pine Westernshop\" \/>\n\t\t<meta property=\"og:description\" content=\"Crossbody Tasche mit Fransen - Handgearbeitete Ledertasche zum Aufh\u00e4ngen an den Hosenschlaufen - R\u00fcckseite ein Fach mit Reissverschlu\u00df f\u00fcr Wichtige Dinge EC Karte und Geld - Prima beim Tanzen oder zum Reiten da hat man alles wichtige dabei und die H\u00e4nde frei - Schulterriemen vorhanden - So das man sie auch zu einer Bodycrosstasche umfunktionieren kann - Gr\u00f6\u00dfe: 17x20cm\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2020\/04\/logo.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2020\/04\/logo.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-02-13T07:39:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-05-08T15:51:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Crossbody Tasche L-162 BK - Lonesome Pine Westernshop\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Crossbody Tasche mit Fransen - Handgearbeitete Ledertasche zum Aufh\u00e4ngen an den Hosenschlaufen - R\u00fcckseite ein Fach mit Reissverschlu\u00df f\u00fcr Wichtige Dinge EC Karte und Geld - Prima beim Tanzen oder zum Reiten da hat man alles wichtige dabei und die H\u00e4nde frei - Schulterriemen vorhanden - So das man sie auch zu einer Bodycrosstasche umfunktionieren kann - Gr\u00f6\u00dfe: 17x20cm\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2020\/04\/logo.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/crossbody-tasche-l-117-black#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/shop-2#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/shop-2#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/shop-2\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/accessoires#listItem\",\"name\":\"ACCESSOIRES\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/accessoires#listItem\",\"position\":3,\"name\":\"ACCESSOIRES\",\"item\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/accessoires\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/accessoires\\\/taschen-accessoires#listItem\",\"name\":\"Taschen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/shop-2#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/accessoires\\\/taschen-accessoires#listItem\",\"position\":4,\"name\":\"Taschen\",\"item\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/accessoires\\\/taschen-accessoires\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/accessoires\\\/taschen-accessoires\\\/handtaschen-accessoires#listItem\",\"name\":\"Handtaschen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/accessoires#listItem\",\"name\":\"ACCESSOIRES\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/accessoires\\\/taschen-accessoires\\\/handtaschen-accessoires#listItem\",\"position\":5,\"name\":\"Handtaschen\",\"item\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/accessoires\\\/taschen-accessoires\\\/handtaschen-accessoires\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/crossbody-tasche-l-117-black#listItem\",\"name\":\"Crossbody Tasche L-162 BK\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/accessoires\\\/taschen-accessoires#listItem\",\"name\":\"Taschen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/crossbody-tasche-l-117-black#listItem\",\"position\":6,\"name\":\"Crossbody Tasche L-162 BK\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product-category\\\/accessoires\\\/taschen-accessoires\\\/handtaschen-accessoires#listItem\",\"name\":\"Handtaschen\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/crossbody-tasche-l-117-black#itempage\",\"url\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/crossbody-tasche-l-117-black\",\"name\":\"Crossbody Tasche L-162 BK - Lonesome Pine Westernshop\",\"description\":\"Crossbody Tasche mit Fransen - Handgearbeitete Ledertasche zum Aufh\\u00e4ngen an den Hosenschlaufen - R\\u00fcckseite ein Fach mit Reissverschlu\\u00df f\\u00fcr Wichtige Dinge EC Karte und Geld - Prima beim Tanzen oder zum Reiten da hat man alles wichtige dabei und die H\\u00e4nde frei - Schulterriemen vorhanden - So das man sie auch zu einer Bodycrosstasche umfunktionieren kann - Gr\\u00f6\\u00dfe: 17x20cm\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/crossbody-tasche-l-117-black#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.lonesomepine.de\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Tasche-RLC-L162-1600-BK-e1699980865439.webp\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/crossbody-tasche-l-117-black\\\/#mainImage\",\"width\":1100,\"height\":1460,\"caption\":\"Crossbody Tasche RCL-162BK\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/crossbody-tasche-l-117-black#mainImage\"},\"datePublished\":\"2020-02-13T08:39:02+01:00\",\"dateModified\":\"2026-05-08T16:51:04+01:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/#organization\",\"name\":\"Lonesome Pine Westernshop\",\"url\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.lonesomepine.de\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo.jpg\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/crossbody-tasche-l-117-black\\\/#organizationLogo\",\"width\":612,\"height\":411,\"caption\":\"logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/product\\\/crossbody-tasche-l-117-black\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/\",\"name\":\"Lonesome Pine Westernshop\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lonesomepine.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Crossbody Tasche L-162 BK - Lonesome Pine Westernshop","description":"Crossbody Tasche mit Fransen - Handgearbeitete Ledertasche zum Aufh\u00e4ngen an den Hosenschlaufen - R\u00fcckseite ein Fach mit Reissverschlu\u00df f\u00fcr Wichtige Dinge EC Karte und Geld - Prima beim Tanzen oder zum Reiten da hat man alles wichtige dabei und die H\u00e4nde frei - Schulterriemen vorhanden - So das man sie auch zu einer Bodycrosstasche umfunktionieren kann - Gr\u00f6\u00dfe: 17x20cm","canonical_url":"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/www.lonesomepine.de\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/shop-2#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/shop-2#listItem","position":2,"name":"Shop","item":"https:\/\/www.lonesomepine.de\/en\/shop-2","nextItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires#listItem","name":"ACCESSOIRES"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires#listItem","position":3,"name":"ACCESSOIRES","item":"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires","nextItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires\/taschen-accessoires#listItem","name":"Taschen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/shop-2#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires\/taschen-accessoires#listItem","position":4,"name":"Taschen","item":"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires\/taschen-accessoires","nextItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires\/taschen-accessoires\/handtaschen-accessoires#listItem","name":"Handtaschen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires#listItem","name":"ACCESSOIRES"}},{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires\/taschen-accessoires\/handtaschen-accessoires#listItem","position":5,"name":"Handtaschen","item":"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires\/taschen-accessoires\/handtaschen-accessoires","nextItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black#listItem","name":"Crossbody Tasche L-162 BK"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires\/taschen-accessoires#listItem","name":"Taschen"}},{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black#listItem","position":6,"name":"Crossbody Tasche L-162 BK","previousItem":{"@type":"ListItem","@id":"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires\/taschen-accessoires\/handtaschen-accessoires#listItem","name":"Handtaschen"}}]},{"@type":"ItemPage","@id":"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black#itempage","url":"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black","name":"Crossbody Tasche L-162 BK - Lonesome Pine Westernshop","description":"Crossbody Tasche mit Fransen - Handgearbeitete Ledertasche zum Aufh\u00e4ngen an den Hosenschlaufen - R\u00fcckseite ein Fach mit Reissverschlu\u00df f\u00fcr Wichtige Dinge EC Karte und Geld - Prima beim Tanzen oder zum Reiten da hat man alles wichtige dabei und die H\u00e4nde frei - Schulterriemen vorhanden - So das man sie auch zu einer Bodycrosstasche umfunktionieren kann - Gr\u00f6\u00dfe: 17x20cm","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/www.lonesomepine.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2020\/02\/Tasche-RLC-L162-1600-BK-e1699980865439.webp","@id":"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black\/#mainImage","width":1100,"height":1460,"caption":"Crossbody Tasche RCL-162BK"},"primaryImageOfPage":{"@id":"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black#mainImage"},"datePublished":"2020-02-13T08:39:02+01:00","dateModified":"2026-05-08T16:51:04+01:00"},{"@type":"Organization","@id":"https:\/\/www.lonesomepine.de\/en\/#organization","name":"Lonesome Pine Westernshop","url":"https:\/\/www.lonesomepine.de\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2020\/04\/logo.jpg","@id":"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black\/#organizationLogo","width":612,"height":411,"caption":"logo"},"image":{"@id":"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/www.lonesomepine.de\/en\/#website","url":"https:\/\/www.lonesomepine.de\/en\/","name":"Lonesome Pine Westernshop","inLanguage":"en-GB","publisher":{"@id":"https:\/\/www.lonesomepine.de\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Lonesome Pine Westernshop -","og:type":"article","og:title":"Crossbody Tasche L-162 BK - Lonesome Pine Westernshop","og:description":"Crossbody Tasche mit Fransen - Handgearbeitete Ledertasche zum Aufh\u00e4ngen an den Hosenschlaufen - R\u00fcckseite ein Fach mit Reissverschlu\u00df f\u00fcr Wichtige Dinge EC Karte und Geld - Prima beim Tanzen oder zum Reiten da hat man alles wichtige dabei und die H\u00e4nde frei - Schulterriemen vorhanden - So das man sie auch zu einer Bodycrosstasche umfunktionieren kann - Gr\u00f6\u00dfe: 17x20cm","og:url":"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black","og:image":"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2020\/04\/logo.jpg","og:image:secure_url":"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2020\/04\/logo.jpg","article:published_time":"2020-02-13T07:39:02+00:00","article:modified_time":"2026-05-08T15:51:04+00:00","twitter:card":"summary","twitter:title":"Crossbody Tasche L-162 BK - Lonesome Pine Westernshop","twitter:description":"Crossbody Tasche mit Fransen - Handgearbeitete Ledertasche zum Aufh\u00e4ngen an den Hosenschlaufen - R\u00fcckseite ein Fach mit Reissverschlu\u00df f\u00fcr Wichtige Dinge EC Karte und Geld - Prima beim Tanzen oder zum Reiten da hat man alles wichtige dabei und die H\u00e4nde frei - Schulterriemen vorhanden - So das man sie auch zu einer Bodycrosstasche umfunktionieren kann - Gr\u00f6\u00dfe: 17x20cm","twitter:image":"https:\/\/www.lonesomepine.de\/wp-content\/uploads\/2020\/04\/logo.jpg"},"aioseo_meta_data":{"post_id":"4279","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"aioseo-web-page-637a09a0c43a3","slug":"web-page","graphName":"WebPage","label":"Web Page","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"created":"2021-07-18 20:44:09","updated":"2026-06-21 17:09:03","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.lonesomepine.de\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.lonesomepine.de\/en\/shop-2\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires\" title=\"ACCESSOIRES\">ACCESSOIRES<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires\/taschen-accessoires\" title=\"Taschen\">Taschen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires\/taschen-accessoires\/handtaschen-accessoires\" title=\"Handtaschen\">Handtaschen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCrossbody Tasche L-162 BK\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.lonesomepine.de\/en\/"},{"label":"Shop","link":"https:\/\/www.lonesomepine.de\/en\/shop-2"},{"label":"ACCESSOIRES","link":"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires"},{"label":"Taschen","link":"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires\/taschen-accessoires"},{"label":"Handtaschen","link":"https:\/\/www.lonesomepine.de\/en\/product-category\/accessoires\/taschen-accessoires\/handtaschen-accessoires"},{"label":"Crossbody Tasche L-162 BK","link":"https:\/\/www.lonesomepine.de\/en\/product\/crossbody-tasche-l-117-black"}],"_links":{"self":[{"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/product\/4279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/comments?post=4279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/media\/11431"}],"wp:attachment":[{"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/media?parent=4279"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/product_brand?post=4279"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/product_cat?post=4279"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.lonesomepine.de\/en\/wp-json\/wp\/v2\/product_tag?post=4279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}